{"id":9004111222937059,"date":"2024-03-04T14:05:48","date_gmt":"2024-03-04T19:05:48","guid":{"rendered":"https:\/\/www.opex.com\/values-principles\/"},"modified":"2026-04-21T20:38:57","modified_gmt":"2026-04-22T00:38:57","slug":"valeurs-et-principes","status":"publish","type":"page","link":"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/","title":{"rendered":"Valeurs et principes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9004111222937059\" class=\"elementor elementor-9004111222937059 elementor-12378\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3297ae6e opex-hero e-flex e-con-boxed e-con e-child\" data-id=\"3297ae6e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4b3d6413 e-con-full e-flex e-con e-child\" data-id=\"4b3d6413\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-665e572 opex-h1-eyebrow elementor-widget elementor-widget-text-editor\" data-id=\"665e572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 propos d&rsquo;OPEX<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a264df2 opex-spacer-mbe-lg-9 opex-spacer-mbe-sm-7 elementor-widget elementor-widget-heading\" data-id=\"2a264df2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Valeurs et principes<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22cccda9 e-flex e-con-boxed e-con e-parent\" data-id=\"22cccda9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-32b72d5a e-flex e-con-boxed e-con e-child\" data-id=\"32b72d5a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bdd8d15 opex-spacer-pbs-8 opex-spacer-pbe-5 elementor-widget elementor-widget-heading\" data-id=\"2bdd8d15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Valeurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a0fa4c e-flex e-con-boxed e-con e-parent\" data-id=\"8a0fa4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7475c1fd elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"7475c1fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Accordion -->\n\t\t<link id='font-awesome-css' href='https:\/\/www.opex.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/www.opex.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_7475c1fd *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_7475c1fd .uc_ac_box\n{\n  overflow:hidden;\n}\n\n#uc_content_accordion_elementor_7475c1fd .ue_heading_title\n{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_7475c1fd .uc_container .uc-heading\n{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;\n  \n}\n#uc_content_accordion_elementor_7475c1fd .uc_container .uc_content\n{\n    display:none;\n}\n\n#uc_content_accordion_elementor_7475c1fd .uc_container .uc-heading span.ue_accordion_icon\n{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n#uc_content_accordion_elementor_7475c1fd .uc_ac_box.uc-item-active span.uc_dactive\n{\n\tdisplay:none;\n}\n#uc_content_accordion_elementor_7475c1fd .uc_ac_box:not(.uc-item-active) span.uc_active\n{\n\tdisplay:none;\n}\n#uc_content_accordion_elementor_7475c1fd span.ue_accordion_icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_7475c1fd .uc_container .uc_btn {\n\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_7475c1fd .ue-item-image img\n{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_7475c1fd\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\t\t\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-080ded5 uc-item-active\" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Int\u00e9grit\u00e9<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" style='display:block'>\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>Int\u00e9grit\u00e9<\/p>\n<p>Par : Dave Stevens, Pr\u00e9sident-directeur g\u00e9n\u00e9ral<\/p>\n<p>\u00ab Je recherche trois qualit\u00e9s lors du recrutement. La premi\u00e8re est l'int\u00e9grit\u00e9 personnelle, la deuxi\u00e8me est l'intelligence, et la troisi\u00e8me est un niveau d'\u00e9nergie \u00e9lev\u00e9. Mais sans la premi\u00e8re, les deux autres vous d\u00e9truiront. \u00bb<\/p>\n<p>\u2013Warren Buffett<\/p>\n<p>Au c\u0153ur de l'int\u00e9grit\u00e9 se trouve le fait d'\u00eatre entier et d'agir de mani\u00e8re coh\u00e9rente dans sa vie. Mais l'int\u00e9grit\u00e9 ne se limite pas \u00e0 agir de mani\u00e8re coh\u00e9rente. C'est agir en accord avec les principes moraux qui dictent notre direction.  <\/p>\n<p>Au d\u00e9but de l'histoire d'OPEX (avant que mon p\u00e8re n'ach\u00e8te l'entreprise), il y avait des personnes occupant des postes de direction cl\u00e9s qui \u00e9taient des menteurs chroniques. Mon p\u00e8re disait que le mensonge faisait tellement partie de leur mode de vie qu'ils mentaient m\u00eame quand la v\u00e9rit\u00e9 \u00e9tait pr\u00e9f\u00e9rable. Apr\u00e8s que mon p\u00e8re a rachet\u00e9 l'entreprise, il a clairement fait savoir que le mensonge ne serait pas tol\u00e9r\u00e9. Jusqu'\u00e0 ce jour, nous pratiquons la v\u00e9rit\u00e9 dans le cadre d'une culture d'int\u00e9grit\u00e9.   <\/p>\n<p>L'int\u00e9grit\u00e9 est un effort de toute une vie pour vivre et agir de mani\u00e8re morale et droite. Je me rappelle chaque jour qu'il y a des gens avec des t\u00e9l\u00e9phones portables. Ils enregistrent les images de notre fa\u00e7on de vivre et de faire des affaires. Lorsque nous regardons les informations de 17 heures et que nous voyons notre image affich\u00e9e en haute d\u00e9finition, serons-nous satisfaits de la fa\u00e7on dont cette image nous a d\u00e9finis ? J'esp\u00e8re qu'ils concluront le reportage en disant : \u00ab C'est un homme d'int\u00e9grit\u00e9. \u00bb    <\/p>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-b91dc34 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">V\u00e9rit\u00e9<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>V\u00e9rit\u00e9<\/p>\n<p>Par : Mark Stevens, Directeur des op\u00e9rations<\/p>\n<p>\u00ab La v\u00e9rit\u00e9 est incontestable. La malveillance peut l'attaquer, l'ignorance peut s'en moquer, mais \u00e0 la fin, elle est l\u00e0. \u00bb<\/p>\n<p>\u2014 Winston Churchill<\/p>\n<p>Dans la soci\u00e9t\u00e9 actuelle, nous avons perdu la notion que nous devrions toujours dire toute la v\u00e9rit\u00e9. Il semble suffisant pour la plupart des gens de simplement ne pas mentir. Je soutiens que si nous disons intentionnellement quelque chose que nous savons induire les gens en erreur, alors en essence, nous mentons. Il y a une grande diff\u00e9rence entre dire toute la v\u00e9rit\u00e9 et dire quelque chose qui est techniquement correct, mais qui serait trompeur si pris au pied de la lettre.   <\/p>\n<p>Chez OPEX, il est important que nous mod\u00e9lisions une culture de v\u00e9rit\u00e9. Il y a des moments o\u00f9 il pourrait sembler opportun d'induire quelqu'un en erreur, mais nous devons r\u00e9sister \u00e0 la tentation. Dire la v\u00e9rit\u00e9 peut dans certains cas nous nuire \u00e0 court terme, mais \u00e0 long terme, cela m\u00e8ne toujours au meilleur r\u00e9sultat.  <\/p>\n<p>M\u00eame si la v\u00e9rit\u00e9 nous co\u00fbte une commande ou nous oblige \u00e0 faire un d\u00e9placement sp\u00e9cial pour voir un client insatisfait, nous pouvons tous dormir tranquilles la nuit sans nous inqui\u00e9ter d'\u00eatre pris en train de mentir, car le mensonge n'est pas acceptable chez OPEX. Nous ne faisons tout simplement pas les affaires \u2013 ou la vie \u2013 de cette fa\u00e7on. <\/p>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-f93e2a3 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">\u00c9quit\u00e9<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>\u00c9quit\u00e9<\/p>\n<p>Par : Ashley Lamb, Administratrice RH<\/p>\n<p>\u00ab Vivez de telle sorte que lorsque vos enfants pensent \u00e0 l'\u00e9quit\u00e9 et \u00e0 l'int\u00e9grit\u00e9, ils pensent \u00e0 vous. \u00bb<\/p>\n<p>\u2014 H. Jackson Brown, Jr.<\/p>\n<p>Nous vivons dans une culture qui nous apprend \u00e0 \u00ab penser \u00e0 soi d'abord \u00bb \u2013 \u00e0 nous-m\u00eames \u2013 quoi qu'il arrive. Mais dans la famille Stevens, nous avons appris \u00e0 faire les choses d'une mani\u00e8re tr\u00e8s diff\u00e9rente. Il ne s'agit pas de savoir si nous recevons un traitement \u00e9quitable, mais si nous le donnons. Notre foi que Dieu contr\u00f4le toutes choses aide vraiment, surtout quand \u00eatre \u00e9quitable est difficile.   <\/p>\n<p>J'ai observ\u00e9 dans notre famille que l'\u00e9quit\u00e9 est une opportunit\u00e9 qu'il faut parfois activement rechercher. Il est important d'examiner comment nos actions affectent les autres : famille, amis, coll\u00e8gues et clients. Ma famille a toujours \u00e9t\u00e9 tr\u00e8s attentive \u00e0 la fa\u00e7on dont elle affecte les autres personnes. Prenez, par exemple, comment OPEX cherche \u00e0 fournir \u00e9quitablement des soins de sant\u00e9 ad\u00e9quats \u00e0 ses employ\u00e9s, quelle que soit leur position dans l'entreprise. Fournir d'excellents soins de sant\u00e9 est simplement une question d'\u00e9quit\u00e9, de faire ce qui est juste.    <\/p>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-d03db65 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Intendance<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><p>Intendance<\/p>\n<p>Par : Al Stevens, Pr\u00e9sident du conseil d'administration<\/p>\n<p>\u00ab De plus, ce qu'on demande des intendants, c'est qu'ils soient trouv\u00e9s fid\u00e8les. \u00bb<\/p>\n<p>\u2014 1 Corinthiens 4:2<\/p>\n<div class=\"et_pb_section et_pb_section_3 et_pb_with_background et_section_regular\">\n<div class=\"et_pb_row et_pb_row_3\">\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_4 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_3 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p>L'intendance est un principe enseign\u00e9 dans la Bible. Un intendant est un gardien \u00e0 qui le propri\u00e9taire a confi\u00e9 la garde et l'investissement de ce qui lui a \u00e9t\u00e9 donn\u00e9 par une utilisation prudente du temps, du talent et de la sagesse pour en am\u00e9liorer la valeur. Un gardien est responsable devant le propri\u00e9taire des r\u00e9sultats produits. Nous sommes les gardiens de tout ce que nous avons dans la vie, y compris OPEX Corporation. C'est une responsabilit\u00e9 impressionnante quand on consid\u00e8re toutes les familles qui d\u00e9pendent d'OPEX pour leur subsistance.    <\/p>\n<p>Nous sommes \u00e9galement conscients de notre besoin d'\u00eatre de bons intendants du monde que Dieu nous a donn\u00e9. En avril 2012, nous avons franchi une \u00e9tape majeure en devenant l'une des plus grandes entreprises commerciales du New Jersey \u00e0 r\u00e9pondre \u00e0 tous nos besoins en \u00e9lectricit\u00e9 gr\u00e2ce \u00e0 l'utilisation de panneaux solaires. L'investissement initial \u00e9tait important, mais il en r\u00e9sultera des \u00e9conomies qui dureront plusieurs d\u00e9cennies et profiteront \u00e0 l'environnement.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-e469c32 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Flexibilit\u00e9 organisationnelle<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p>Flexibilit\u00e9 <strong>organisationnelle<\/strong><\/p>\n<p>Par : Jon Stevens, Directeur d'OMATION<\/p>\n<p>\u00ab <em>Soyez clair sur votre objectif mais flexible sur le processus.<\/em> \u00bb<\/p>\n<p>\u2014 Brian Tracy<\/p>\n<p>La flexibilit\u00e9 organisationnelle est la capacit\u00e9 \u00e0 comprendre et \u00e0 g\u00e9rer le changement. Je crois que le changement au sein d'OPEX peut \u00eatre structur\u00e9 dans notre culture, notre industrie et nos employ\u00e9s. Quand je pense \u00e0 la flexibilit\u00e9, je pense \u00e0 un \u00e9lastique. Vous pouvez \u00e9tirer et changer la forme d'un \u00e9lastique. Vous pouvez tirer un \u00e9lastique dans toutes les directions. Cependant, si vous le tirez trop loin, il se casse.     <\/p>\n<p>En regardant vingt ans en arri\u00e8re, je peux penser \u00e0 de nombreux exemples o\u00f9 OPEX a d\u00e9montr\u00e9 sa flexibilit\u00e9 organisationnelle. Quelques exemples majeurs se d\u00e9marquent. En 2003, nous commencions tout juste \u00e0 nous familiariser avec le march\u00e9 des scanners. Nous avons eu une excellente id\u00e9e de placer un scanner au-dessus de notre bureau Rapid Extraction. Ce fut un \u00e9norme succ\u00e8s. Depuis lors, nous avons modifi\u00e9 le produit de nombreuses fois pour r\u00e9pondre aux demandes des clients.     <\/p>\n<p>L'exemple le plus marquant de flexibilit\u00e9 organisationnelle est probablement notre entr\u00e9e sur le march\u00e9 de l'automatisation d'entrep\u00f4t. Je crois que notre \u00e9lastique est plus \u00e9tir\u00e9 que jamais dans ce nouveau march\u00e9 de produits. Pourtant, nous n'avons pas atteint le point de rupture car m\u00eame si nous sommes flexibles, nous restons dans les limites de nos autres principes et valeurs d'entreprise.  <\/p>\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab6\" class=\"uc_ac_box elementor-repeater-item-c2ac474 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Service<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<p>Service<\/p>\n<p>Par : Jen Hale, membre de la famille Stevens<\/p>\n<p>\u00ab<em>La premi\u00e8re responsabilit\u00e9 d'un leader est de d\u00e9finir la r\u00e9alit\u00e9. La derni\u00e8re est de dire merci. Entre les deux, le leader est un serviteur.  <\/em>\u00ab<\/p>\n<p>\u2014 Max De Pree<\/p>\n<p>En grandissant, j'ai commenc\u00e9 \u00e0 travailler dans le d\u00e9partement RH d'OPEX. L'une de mes t\u00e2ches pr\u00e9f\u00e9r\u00e9es \u00e9tait d'aider \u00e0 planifier les d\u00e9jeuners d'entreprise qui avaient lieu chaque mois. Lorsque nous commandions la nourriture et pr\u00e9parions le d\u00e9jeuner, j'\u00e9tais toujours \u00e9tonn\u00e9e de voir combien de personnes voulaient aider. Que ce soit pour aller chercher la nourriture, aller au magasin pour acheter de la nourriture si nous faisions un barbecue, ou installer les tables, il n'y avait jamais de p\u00e9nurie d'aide. J'\u00e9tais \u00e9galement frapp\u00e9e par le fait que nous n'avions jamais de probl\u00e8me pour trouver des managers pour servir la nourriture. Chaque fois que nous demandions, la r\u00e9ponse \u00e9tait toujours \u00ab oui \u00bb.     <\/p>\n<p>Non seulement c'\u00e9tait quelque chose que les managers aimaient faire, mais c'\u00e9tait parfois assez divertissant pour nous tous de regarder ! Certains \u00e9taient meilleurs que d'autres. Cependant, leurs attitudes \u00e9taient toujours positives. C'\u00e9tait humiliant \u00e0 regarder et c'\u00e9tait encore un rappel de combien j'\u00e9tais reconnaissante de travailler quelque part o\u00f9 les managers aimaient servir ceux qui travaillaient pour eux.   <\/p>\n<p>En grandissant, en d\u00e9m\u00e9nageant et en travaillant pour d'autres organisations, j'ai r\u00e9alis\u00e9 \u00e0 quel point cette valeur d'entreprise est essentielle. Elle nous force tous \u00e0 regarder au-del\u00e0 de notre \u00e9go\u00efsme et \u00e0 servir ceux qui nous entourent au travail, dans notre communaut\u00e9 et dans nos foyers. Si nous cultivons la valeur du service envers ceux qui nous entourent, des gens ordinaires feront des choses extraordinaires. Je suis reconnaissante d'avoir vu, et de continuer \u00e0 voir, ce trait se d\u00e9velopper chez OPEX.   <\/p>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab7\" class=\"uc_ac_box elementor-repeater-item-b4ecc13 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">\u00c9thique de travail forte<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<p>\u00c9thique de travail forte<\/p>\n<p>Par : Alex Stevens, Pr\u00e9sident de l'automatisation d'entrep\u00f4t<\/p>\n<p>\u00ab Travailler dur devient une habitude, une sorte de plaisir s\u00e9rieux. Vous obtenez une satisfaction personnelle en vous poussant \u00e0 la limite, sachant que tous les efforts vont payer. \u00bb<\/p>\n<p>\u2014 Mary Lou Retton<\/p>\n<\/p>\n<p>Tout au long de nos vies et de nos carri\u00e8res, la plupart d'entre nous auront diff\u00e9rents emplois, r\u00f4les et responsabilit\u00e9s. Lorsque nous travaillons dur dans n'importe quel r\u00f4le, nos exp\u00e9riences nous aideront in\u00e9vitablement \u00e0 l'avenir. Dans une organisation de la taille d'OPEX, il y a de nombreuses interd\u00e9pendances. Ce qui me motive (et motive les autres) \u00e0 travailler dur dans mon travail, c'est de savoir que dans cette organisation, nous sommes d\u00e9pendants les uns des autres. Si je travaille dur et fais du bon travail, alors d'une petite mani\u00e8re, cela permet aux autres personnes de l'organisation de s'\u00e9panouir et de continuer \u00e0 faire leur travail.    <\/p>\n<p>Nous avons tous un r\u00f4le actif \u00e0 jouer en travaillant dur, en faisant de notre mieux et en faisant avancer l'organisation pour que nous puissions tous continuer \u00e0 subvenir aux besoins de nos familles.<\/p>\n<p>On cite souvent Thomas Jefferson disant : \u00ab Je crois beaucoup en la chance. Plus je travaille dur, plus j'ai de la chance. \u00bb Le concept de base derri\u00e8re cela est que plus nous travaillons dur, plus nous nous ouvrons \u00e0 des opportunit\u00e9s et plus nous avons de chances de r\u00e9ussir. <\/p>\n<p>En tant qu'organisation, j'aime penser que si nous continuons tous \u00e0 travailler dur, \u00e0 faire un excellent travail dans notre fonction sp\u00e9cifique, alors nous continuerons \u00e0 fabriquer d'excellents produits, \u00e0 innover et \u00e0 cr\u00e9er plus d'opportunit\u00e9s pour nous-m\u00eames \u00e0 l'avenir.<\/p>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab8\" class=\"uc_ac_box elementor-repeater-item-4f41718 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">L'humain avant la position<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<p>L'humain avant la position<\/p>\n<p>Par : Drew Stevens, VP, D\u00e9veloppement commercial mondial \u2013 Automatisation d'entrep\u00f4t<\/p>\n<p>\u00ab Nous ne tournerons jamais \u2013 et je dis bien jamais \u2013 le dos \u00e0 nos employ\u00e9s. \u00bb<\/p>\n<p>\u2014 Howard Schultz, Starbucks<\/p>\n<p>De nombreuses entreprises consid\u00e8rent leurs employ\u00e9s comme des actifs poss\u00e9dant des comp\u00e9tences sp\u00e9cifiques. Les comp\u00e9tences des employ\u00e9s d\u00e9finissent leur rang dans la hi\u00e9rarchie de l'organisation. <\/p>\n<p>Reconna\u00eetre les employ\u00e9s comme des \u00eatres humains, et non comme des ensembles de comp\u00e9tences, favorise une culture d'entreprise \u00e9galitaire qui minimise la hi\u00e9rarchie et brise les barri\u00e8res artificielles. Les employ\u00e9s peuvent se connecter avec la direction d'OPEX sur un niveau professionnel et personnel car ils sont valoris\u00e9s en tant que personnes, non d\u00e9finis par leur position. <\/p>\n<p>\u00ab L'humain avant la position \u00bb dicte la fa\u00e7on dont nous traitons les autres chez OPEX. Mais cela refl\u00e8te \u00e9galement une attitude personnelle sur la fa\u00e7on dont nous nous voyons nous-m\u00eames. Si nous croyons qu'un titre professionnel ne nous rend pas sup\u00e9rieurs aux autres, alors nous traiterons naturellement nos coll\u00e8gues avec respect.  <\/p>\n<p>\u00ab L'humain avant la position \u00bb a \u00e9t\u00e9 une valeur d'entreprise d'OPEX depuis sa cr\u00e9ation. Les pratiques commerciales d'OPEX mod\u00e9lisent cette valeur. Les employ\u00e9s ont un acc\u00e8s ouvert aux dirigeants dans un environnement qui minimise l'importance du titre. La culture d'OPEX renforce l'accent mis sur les personnes.   <\/p>\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab9\" class=\"uc_ac_box elementor-repeater-item-bedcf5e \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Confiance<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p><strong>Confiance<\/strong><\/p>\n<p>Par : Kristen Miranda, Coordinatrice de soutien ex\u00e9cutif<\/p>\n<p>\u00ab <em>Il faut vingt ans pour b\u00e2tir une r\u00e9putation et cinq minutes pour la ruiner.<\/em> \u00bb<\/p>\n<p>\u2014 Warren Buffett<\/p>\n<p>La confiance est quelque chose que nous accordons r\u00e9guli\u00e8rement sans m\u00eame nous en rendre compte. Lorsque nous nous asseyons sur une chaise, nous lui faisons confiance pour nous soutenir. Lorsque nous entrons dans un b\u00e2timent, nous avons confiance que le toit ne s'effondrera pas sur nous. Mais la confiance est bien plus que de croire que les choses ne nous d\u00e9cevront pas. La confiance implique des personnes.    <\/p>\n<p>Au cours des derni\u00e8res ann\u00e9es de travail chez OPEX, j'ai vu comment la confiance est tiss\u00e9e dans presque tout ce que nous faisons. Dans mon poste de Coordinatrice des salons professionnels, j'ai appris que je dois faire confiance \u00e0 ceux qui m'entourent pour m'aider \u00e0 accomplir mon travail. Je dois faire confiance \u00e0 la Production pour construire correctement les machines, \u00e0 l'Exp\u00e9dition pour les envoyer au bon endroit, au Service pour venir installer les machines, et aux Ventes pour pr\u00e9senter le bon message \u00e0 nos clients et prospects. Dans une organisation o\u00f9 le travail d'\u00e9quipe est n\u00e9cessaire, la confiance est essentielle.   <\/p>\n<p>Mais la confiance va dans les deux sens. Il est non seulement important de faire confiance aux autres, mais il est important d'\u00eatre digne de confiance. Pour moi, \u00eatre quelqu'un en qui les gens peuvent avoir confiance est tout aussi important que de faire confiance aux autres.  <\/p>\n<p>En tant que famille, nous reconnaissons que chaque employ\u00e9 place sa confiance en nous. Nous savons que vous nous faites confiance pour votre subsistance. Ce n'est pas quelque chose que nous prenons \u00e0 la l\u00e9g\u00e8re. Lorsque des d\u00e9cisions sont prises concernant la croissance et l'expansion, l'une des grandes consid\u00e9rations est : Pourrons-nous maintenir ce poste si la croissance ne continue pas au rythme actuel ? L'une des raisons pour lesquelles nous posons cette question est que chaque employ\u00e9 fait confiance \u00e0 OPEX pour fournir son prochain ch\u00e8que de paie. Nous reconnaissons que non seulement vous nous avez fait confiance, mais que d'une certaine mani\u00e8re, vous avez mis le bien-\u00eatre de votre famille entre nos mains. Pour notre famille, c'est important.      <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\n\n<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59c4d359 e-flex e-con-boxed e-con e-child\" data-id=\"59c4d359\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2635a44a opex-spacer-pbs-8 opex-spacer-pbe-5 elementor-widget elementor-widget-heading\" data-id=\"2635a44a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principes <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c547472 elementor-widget elementor-widget-spacer\" data-id=\"7c547472\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64fec669 e-flex e-con-boxed e-con e-parent\" data-id=\"64fec669\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f845546 elementor-widget elementor-widget-ucaddon_content_accordion\" data-id=\"1f845546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Accordion -->\n\n<style>\/* widget: Content Accordion *\/\n\n\n\n#uc_content_accordion_elementor_1f845546 *{\n  box-sizing: border-box;\n}\n\n#uc_content_accordion_elementor_1f845546 .uc_ac_box\n{\n  overflow:hidden;\n}\n\n#uc_content_accordion_elementor_1f845546 .ue_heading_title\n{\n  margin:0;\n  flex-grow:1;\n  display:flex;\n  flex-direction:row;\n}\n\n#uc_content_accordion_elementor_1f845546 .uc_container .uc-heading\n{\n\tdisplay:flex;\n    align-items:center;\n\toverflow:hidden;\n\tcursor:pointer;\n  \n}\n#uc_content_accordion_elementor_1f845546 .uc_container .uc_content\n{\n    display:none;\n}\n\n#uc_content_accordion_elementor_1f845546 .uc_container .uc-heading span.ue_accordion_icon\n{\n\tdisplay:flex;\n    align-items:center;\n   \tjustify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n}\n#uc_content_accordion_elementor_1f845546 .uc_ac_box.uc-item-active span.uc_dactive\n{\n\tdisplay:none;\n}\n#uc_content_accordion_elementor_1f845546 .uc_ac_box:not(.uc-item-active) span.uc_active\n{\n\tdisplay:none;\n}\n#uc_content_accordion_elementor_1f845546 span.ue_accordion_icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_accordion_elementor_1f845546 .uc_container .uc_btn {\n\n    text-align: center;\n    display: inline-block;\n    text-decoration: none;\n    transition: ease-in-out all 0.25s;\n}\n\n#uc_content_accordion_elementor_1f845546 .ue-item-image img\n{\n  width:100%;\n  display:block;\n  object-fit:cover;\n}\n\n<\/style>\n\n<div class=\"uc_material_accordion  \"  id=\"uc_content_accordion_elementor_1f845546\"  data-name=\"\" data-scroll=\"off\" data-offset=\"0\" data-closeothers=\"true\" data-set-hash=\"false\" >\n  <div class=\"uc_container uc-items-wrapper\">\n    \n\t\t\n\n<div id=\"#ue-tab1\" class=\"uc_ac_box elementor-repeater-item-080ded5 uc-item-active\" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Mener toutes les affaires de mani\u00e8re \u00e9quitable et honn\u00eate.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" style='display:block'>\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_section et_pb_section_1 et_pb_with_background et_section_regular\">\n<div class=\"et_pb_row et_pb_row_1 et_pb_gutters1\">\n<p class=\"et_pb_column et_pb_column_1_2 et_pb_column_1 et_pb_css_mix_blend_mode_passthrough et_pb_column_empty\">Mener toutes les affaires de mani\u00e8re \u00e9quitable et honn\u00eate.<\/p>\n<div class=\"et_pb_column et_pb_column_1_2 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p>Michael McLain, Directeur r\u00e9gional du service<\/p>\n<p>\u00ab Mener toutes les affaires de mani\u00e8re \u00e9quitable et honn\u00eate \u00bb est le premier des neuf principes d'entreprise, et \u00e0 juste titre, car c'est peut-\u00eatre le principe le plus crucial auquel toute entreprise peut esp\u00e9rer adh\u00e9rer.<\/p>\n<p>Nous devons nous rappeler que sans nos clients, nous n'avons pas d'entreprise, donc nous ne devons pas essayer de les \u00ab tromper \u00bb, pour ainsi dire. Cela signifie \u00eatre franc sur ce que vous pouvez et ne pouvez pas faire pour vos clients. Reconna\u00eetre ces limites et les respecter est essentiel.  <\/p>\n<p>Id\u00e9alement, nous devrions nous efforcer de faire en sorte que chaque client se sente comme notre unique client. Rappelez-vous, nos \u00ab affaires \u00bb ne se limitent pas \u00e0 nos relations avec nos clients, mais incluent aussi nos interactions au sein de l'entreprise elle-m\u00eame. Lorsque nous sommes \u00ab \u00e9quitables \u00bb et \u00ab honn\u00eates \u00bb avec nos coll\u00e8gues (que ce soit le Support technique, la Direction ou un autre Technicien de terrain), nous ne faisons que renforcer les fondations de l'entreprise et ainsi assurer la stabilit\u00e9 et la s\u00e9curit\u00e9 de nos propres moyens de subsistance.  <\/p>\n<p>Donc, lorsque nous pensons \u00e0 \u00ab mener toutes les affaires de mani\u00e8re \u00e9quitable et honn\u00eate \u00bb, nous devons nous rappeler que ce n'est pas seulement r\u00e9parer un \u00e9quipement en panne : C'est tout ce que nous faisons ; chaque document que nous remplissons, chaque conversation que nous avons, et chaque regard que nous croisons.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab2\" class=\"uc_ac_box elementor-repeater-item-b91dc34 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">\u00c9couter et r\u00e9pondre aux besoins des clients.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p>\u00c9couter et r\u00e9pondre aux besoins des clients.<\/p>\n<p>Lonnie Amico, R\u00e9ceptionniste<\/p>\n<div class=\"et_pb_section et_pb_section_2 et_pb_with_background et_section_regular\">\n<div class=\"et_pb_row et_pb_row_2\">\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_3 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_2 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p>\u00c9couter. Que signifie \u00ab \u00e9couter \u00bb quelqu'un ? Pour moi, c'est \u00eatre concentr\u00e9 et pleinement pr\u00e9sent \u00e0 ce qui est dit. Vous ne pouvez pas \u00eatre distrait et \u00e9couter partiellement ou penser \u00e0 autre chose pendant que la personne vous parle. Un bon auditeur ne pense pas \u00e0 l'avance \u00e0 quel type de r\u00e9ponse il ou elle va donner pendant que la personne parle ; le bon auditeur \u00e9coute simplement ce qui est dit.    <\/p>\n<p>Souvent, je suis le premier contact pour un client ou un prospect lorsqu'ils appellent OPEX. Il est donc tr\u00e8s important d'\u00eatre agr\u00e9able et de faire de mon mieux pour r\u00e9pondre \u00e0 leurs questions. <\/p>\n<p>Si un client a un probl\u00e8me de personnel ou de produit, je veux r\u00e9soudre le probl\u00e8me le plus rapidement possible pour que ce client ait une autre raison de rester fid\u00e8le \u00e0 OPEX. Si un prospect appelle, je veux m'assurer que son exp\u00e9rience avec OPEX est favorable ; et cela commence avec moi. Lorsque nous \u00e9coutons attentivement et r\u00e9pondons rapidement avec des r\u00e9ponses \u00e0 leurs besoins, cela augmente la probabilit\u00e9 qu'ils deviennent clients.  <\/p>\n<p>Il y a eu des fois o\u00f9 on m'a pos\u00e9 une question d'un client \u00e0 laquelle je ne pouvais pas r\u00e9pondre. Quand cela arrive, je leur fais savoir que je vais les mettre en contact avec quelqu'un qui je sais peut les aider. <\/p>\n<p>Le non-n\u00e9gociable pour tout r\u00e9ceptionniste \u2013 en fait, pour nous tous \u2013 est simplement ceci : \u00ab \u00c9couter et r\u00e9pondre aux besoins du client. \u00bb<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab3\" class=\"uc_ac_box elementor-repeater-item-f93e2a3 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Reconna\u00eetre la valeur de l'individu.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_section et_pb_section_1 et_pb_with_background et_section_regular\">\n<div class=\"et_pb_row et_pb_row_1 et_pb_gutters1\">\n<p class=\"et_pb_column et_pb_column_1_2 et_pb_column_1 et_pb_css_mix_blend_mode_passthrough et_pb_column_empty\">Reconna\u00eetre la valeur de l'individu.<\/p>\n<div class=\"et_pb_column et_pb_column_1_2 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p>Vinay Shah, Superviseur d'ing\u00e9nierie \u2013 Support au d\u00e9veloppement des syst\u00e8mes<\/p>\n<p>Dans une crise, votre famille est votre pilier et votre syst\u00e8me de soutien sur lequel vous pouvez compter pour naviguer dans les eaux troubles. Pendant les p\u00e9riodes difficiles, nous r\u00e9alisons \u00e0 quel point notre famille et nos amis comptent vraiment pour nous. Je suis tr\u00e8s chanceux d'avoir deux familles : ma famille de sang et ma famille OPEX.  <\/p>\n<p>Lorsque ma propre famille a travers\u00e9 une crise, ma famille OPEX \u00e9tait l\u00e0 pour nous tout au long du processus. La famille Stevens a envoy\u00e9 des fleurs \u00e0 l'h\u00f4pital. Mes coll\u00e8gues et sup\u00e9rieurs s'assuraient toujours de demander comment allait ma femme et si j'avais besoin de quoi que ce soit. Malgr\u00e9 leurs horaires charg\u00e9s et leur statut de propri\u00e9taires, Mark et Dave Stevens se sont assur\u00e9s d'obtenir des nouvelles r\u00e9guli\u00e8res de l'\u00e9tat de sant\u00e9 de ma femme.   <\/p>\n<p>Ce n'est pas inhabituel pour OPEX. C'est une entreprise qui se consacre \u00e0 reconna\u00eetre chaque individu et \u00e0 le soutenir dans les bons comme dans les mauvais moments. Il a \u00e9t\u00e9 r\u00e9confortant de voir comment les employ\u00e9s d'OPEX sont pr\u00eats \u00e0 aider les autres \u00e0 surmonter les \u00e9v\u00e9nements tragiques qui surviennent de temps \u00e0 autre, tels que le d\u00e9c\u00e8s d'\u00eatres chers, les incendies de maison et les crises de sant\u00e9 familiales. Qu'il s'agisse d'offrir un soutien financier, un soutien moral ou des horaires flexibles, OPEX est toujours l\u00e0 pour aider.   <\/p>\n<p>La direction d'OPEX excelle dans la prise en charge de ses employ\u00e9s, et je suis honor\u00e9 de faire partie d'une excellente organisation avec des gens formidables.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab4\" class=\"uc_ac_box elementor-repeater-item-d03db65 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Maintenir une gestion financi\u00e8re prudente, qui dictera la croissance future.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_section et_pb_section_1 et_pb_with_background et_section_regular\">\n<div class=\"et_pb_row et_pb_row_1 et_pb_gutters1\">\n<p class=\"et_pb_column et_pb_column_1_2 et_pb_column_1 et_pb_css_mix_blend_mode_passthrough et_pb_column_empty\">Maintenir une gestion financi\u00e8re prudente, qui dictera la croissance future.<\/p>\n<div class=\"et_pb_column et_pb_column_1_2 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\n<p>Melissa Rainho, contr\u00f4leuse adjointe<\/p>\n<p>Le principe du maintien d'une gestion financi\u00e8re prudente ne m'a jamais paru aussi \u00e9vident qu'au cours des derni\u00e8res ann\u00e9es. Tant sur le plan personnel que professionnel, j'ai vu des individus et des entreprises lutter parce qu'ils n'agissaient pas en tant que gestionnaires de leurs finances. <\/p>\n<p>Depuis le d\u00e9but de la pand\u00e9mie, nous avons tous \u00e9t\u00e9 t\u00e9moins des d\u00e9fis de la cha\u00eene d'approvisionnement mondiale et des retomb\u00e9es \u00e9conomiques. Le maintien d'une gestion financi\u00e8re prudente vous aide non seulement \u00e0 garder la t\u00eate hors de l'eau pendant les p\u00e9riodes difficiles, mais il vous permet \u00e9galement de continuer \u00e0 cro\u00eetre et \u00e0 profiter des opportunit\u00e9s disponibles. Je ne doute pas que ce principe nous a aid\u00e9s \u00e0 naviguer dans les eaux pendant cette p\u00e9riode.  <\/p>\n<p>Il est important de se rappeler que nous sommes tous les intendants des finances de l'entreprise. Notre croissance d\u00e9pend des d\u00e9cisions que nous prenons tous dans nos r\u00f4les quotidiens. De l'achat de fournitures \u00e0 la g\u00e9n\u00e9ration de revenus, en passant par la prudence lors des d\u00e9placements, toutes ces responsabilit\u00e9s ont un impact direct sur notre croissance future.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab5\" class=\"uc_ac_box elementor-repeater-item-e469c32 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\"> Avancer continuellement et d\u00e9lib\u00e9r\u00e9ment pour assurer la survie continue de l'entreprise.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">Avancer continuellement et d\u00e9lib\u00e9r\u00e9ment pour assurer la survie continue de l'entreprise.<\/div>\n<div class=\"et_pb_text_inner\">Mike Sparango, superviseur de l'ing\u00e9nierie m\u00e9canique<\/div>\n<\/div>\n<div>\n<p>L'expression am\u00e9ricaine bien connue \u00ab&nbsp;\u00eatre comme un cerf pris dans les phares&nbsp;\u00bb d\u00e9signe une personne stup\u00e9faite ou incapable de parler lorsqu'elle est prise au d\u00e9pourvu. Au lieu de r\u00e9agir, elle se fige compl\u00e8tement. <\/p>\n<p>Dans un environnement commercial en \u00e9volution rapide, nous ne voulons jamais \u00eatre pris au d\u00e9pourvu ou ne pas r\u00e9agir aux changements ou aux \u00e9volutions soudaines. OPEX s'engage \u00e0 \u00e9voluer dans une direction qui soit logique pour l'environnement actuel ainsi que pour les besoins futurs de l'entreprise. Nos employ\u00e9s g\u00e8rent les t\u00e2ches d'aujourd'hui, tout en reconnaissant qu'un march\u00e9 en \u00e9volution rapide peut n\u00e9cessiter un autre ensemble de comp\u00e9tences pour les missions futures.  <\/p>\n<p>Nous pensons qu'il faut avancer continuellement et d\u00e9lib\u00e9r\u00e9ment, sinon vous risquez de prendre du retard et d'\u00e9chouer. Nous vivons ce principe quotidiennement en r\u00e9investissant continuellement dans les produits gr\u00e2ce \u00e0 des processus d'ing\u00e9nierie et de fabrication plus sophistiqu\u00e9s, \u00e0 des am\u00e9liorations logicielles ax\u00e9es sur le client et \u00e0 des configurations de cellules de travail bien d\u00e9finies pour l'assemblage des machines. <\/p>\n<p>Par exemple, en 2007, nous sommes entr\u00e9s sur le march\u00e9 du tri du courrier mixte avec un produit innovant pour le stockage et le tri du courrier \u00e0 haute densit\u00e9&nbsp;: le trieur de courrier Mail Matrix\u00ae. Ce trieur de courrier a ensuite donn\u00e9 naissance \u00e0 une id\u00e9e de produit qui pourrait \u00eatre l'une des initiatives les plus audacieuses de notre histoire&nbsp;: et si, au lieu de livrer une enveloppe dans un casier, vous inversiez la direction et r\u00e9cup\u00e9riez dans un casier non pas une enveloppe, mais un produit&nbsp;? Avec cette id\u00e9e, le \u00ab&nbsp;Perfect Pick&nbsp;\u00bb est n\u00e9, et notre activit\u00e9 a d\u00e9lib\u00e9r\u00e9ment progress\u00e9.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab6\" class=\"uc_ac_box elementor-repeater-item-c2ac474 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\"> S'affranchir des traditions et des conventions si une meilleure m\u00e9thode peut \u00eatre con\u00e7ue.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">S'affranchir des traditions et des conventions si une meilleure m\u00e9thode peut \u00eatre con\u00e7ue.<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">Tanya Hamlin, analyste de la conception des processus<\/div>\n<\/div>\n<div>\n<p>Depuis plus de 45&nbsp;ans, OPEX Corporation s'est toujours affranchie des traditions et des conventions en concevant de meilleures m\u00e9thodes dans tous nos produits et leurs r\u00e9visions. Il en va de m\u00eame pour les cha\u00eenes de production d'OPEX. Nous avons commenc\u00e9 il y a quelques ann\u00e9es en utilisant des robots collaboratifs, ce qui nous a fait entrer dans l'industrie&nbsp;3.0. R\u00e9cemment, la production a commenc\u00e9 \u00e0 se plonger dans l'industrie&nbsp;4.0 en utilisant une application IIoT (Internet industriel des objets) appel\u00e9e \u00ab&nbsp;Tulip&nbsp;\u00bb. Tulip fournit des donn\u00e9es rapidement, r\u00e9pondant aux demandes des clients et aux exigences de conformit\u00e9.    <\/p>\n<p>Les donn\u00e9es produites par Tulip aident nos services de production \u00e0 construire plus rapidement et plus intelligemment tout en \u00e9tant en mesure de diffuser les r\u00e9sultats en temps r\u00e9el. M\u00eame si cela signifiait s'\u00e9loigner de la cha\u00eene de production traditionnelle d'OPEX, le passage de notre cha\u00eene Sure Sort iBot \u00e0 une application IIoT s'est av\u00e9r\u00e9 \u00eatre une meilleure m\u00e9thode. Nous avons \u00e9limin\u00e9 la n\u00e9cessit\u00e9 d'extraire les donn\u00e9es de notre syst\u00e8me de planification des ressources de l'entreprise (ERP) un mois apr\u00e8s l'assemblage pour d\u00e9terminer notre qualit\u00e9 de production et les \u00ab&nbsp;occasions faciles&nbsp;\u00bb n\u00e9cessaires \u00e0 l'am\u00e9lioration continue. D\u00e9sormais, nous pouvons communiquer rapidement et efficacement les points pr\u00e9occupants.   <\/p>\n<p>OPEX concevra toujours de meilleures m\u00e9thodes pour \u00eatre un leader mondial dans les secteurs que nous servons. Nous nous efforcerons \u00e9galement d'apporter cette m\u00eame t\u00e9nacit\u00e9 \u00e0 l'am\u00e9lioration de nos cha\u00eenes de production dans le monde de la fabrication. Nous sommes impatients de voir ce que l'industrie&nbsp;5.0 apportera.  <\/p>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab7\" class=\"uc_ac_box elementor-repeater-item-b4ecc13 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\">Se concentrer sur l'expansion de l'entreprise uniquement dans les domaines connexes.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">Se concentrer sur l'expansion de l'entreprise uniquement dans les domaines connexes.<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">George Muttathil, ing\u00e9nieur en m\u00e9canique<\/div>\n<div>\n<p>Ce principe a \u00e9t\u00e9 soigneusement choisi par nos fondateurs pour nous rappeler que lorsque nous essayons de nous \u00e9tendre \u00e0 de nouveaux domaines, nous ne devons pas trop nous \u00e9loigner de ce qui a fait notre succ\u00e8s dans le pass\u00e9.<\/p>\n<p>En apparence, il peut sembler que ce principe contredit ce qu'OPEX a fait historiquement. OPEX a commenc\u00e9 comme une entreprise de traitement des versements de paiements, puis s'est \u00e9tendue \u00e0 la num\u00e9risation de documents num\u00e9riques, puis au tri, puis \u00e0 l'entreposage robotis\u00e9. \u00c0 premi\u00e8re vue, il pourrait sembler que nous nous sommes \u00e9cart\u00e9s de notre voie&nbsp;; cependant, le fait qu'OPEX ait connu un grand succ\u00e8s tout en s'\u00e9tendant \u00e0 chacun de ces nouveaux domaines sugg\u00e8re qu'il y a plus \u00e0 cela.  <\/p>\n<p>Il n'est pas courant qu'une entreprise entre avec succ\u00e8s sur un nouveau march\u00e9. OPEX a r\u00e9ussi \u00e0 le faire \u00e0 plusieurs reprises avec un tr\u00e8s haut degr\u00e9 de succ\u00e8s. Ce n'est pas un accident, et cela ne s'est pas produit du jour au lendemain. Cette large expansion du portefeuille de produits d'OPEX s'est \u00e9tendue sur plusieurs d\u00e9cennies et a \u00e9t\u00e9 un lent processus en deux \u00e9tapes. Tout d'abord, OPEX trouve des moyens de faire les choses mieux que la concurrence, puis nous appliquons ce que nous avons appris dans d'autres domaines. Notre engagement envers ce principe est ce qui a assur\u00e9 notre succ\u00e8s.     <\/p>\n<p>Bien que nous essayions de \u00ab&nbsp;rester dans notre voie&nbsp;\u00bb, OPEX trouve constamment des moyens d'\u00e9largir notre voie tout en restant fid\u00e8le \u00e0 notre objectif.<\/p>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab8\" class=\"uc_ac_box elementor-repeater-item-4f41718 \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\"> Minimiser les niveaux de gestion afin de maximiser l'autonomie des employ\u00e9s.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">Minimiser les niveaux de gestion afin de maximiser l'autonomie des employ\u00e9s.<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">Jon (JP) Longshaw, chef de programme<\/div>\n<div>\n<p>La premi\u00e8re fois que j'ai entendu le principe&nbsp;n\u00b0&nbsp;8, j'ai pens\u00e9 avec un certain cynisme&nbsp;: \u00ab&nbsp;OPEX a des gestionnaires comme n'importe quelle autre organisation.&nbsp;\u00bb Mais avec le temps, j'ai r\u00e9alis\u00e9 qu'OPEX est vraiment unique dans sa structure et son approche de la gestion, ce qui entra\u00eene des diff\u00e9rences essentielles que vous ne trouverez pas dans la plupart des entreprises. <\/p>\n<p>La premi\u00e8re est l'accessibilit\u00e9. Il est ancr\u00e9 dans la philosophie de l'entreprise depuis le d\u00e9but que les employ\u00e9s ont un acc\u00e8s direct aux propri\u00e9taires et \u00e0 la haute direction. La seconde est l'autonomie. Les employ\u00e9s ont la possibilit\u00e9 de participer directement au processus d\u00e9cisionnel de l'entreprise sans avoir \u00e0 passer par plusieurs niveaux de gestion.   <\/p>\n<p>Ne vous m\u00e9prenez pas. OPEX a une structure de gestion en place. Il doit y avoir un PDG, un pr\u00e9sident, etc. pour fonctionner correctement. Mais la diff\u00e9rence ici est que les personnes qui les suivent sont habilit\u00e9es \u00e0 prendre des d\u00e9cisions qui contribueront au succ\u00e8s de l'entreprise. Il est rafra\u00eechissant de travailler dans un endroit o\u00f9 vous avez un acc\u00e8s direct au sommet, o\u00f9 vous avez la ma\u00eetrise des d\u00e9cisions et o\u00f9 vous avez un int\u00e9r\u00eat direct dans ce que vous pensez \u00eatre le mieux pour l'entreprise.    <\/p>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n\n\n<div id=\"#ue-tab9\" class=\"uc_ac_box elementor-repeater-item-bedcf5e \" style=\"background-color:;\">\n  <div class=\"uc-heading uc_trigger\">\n    <span class=\"uc_dactive bbb ue_accordion_icon\"><i class='fas fa-plus'><\/i><\/span> \n    <span class=\"uc_active bbb ue_accordion_icon\"><i class='fas fa-minus'><\/i><\/span>\n    <div class=\"ue_heading_title\"> \u00c9liminer l'attitude du \u00ab&nbsp;ce n'est pas mon travail&nbsp;\u00bb.<\/div>\n  <\/div>\n  \n  <div class=\"uc_content\" >\n        \n      \n         \n                      \n            <div class=\"ue-item-title\"><\/div>\n      \n              <div class=\"ue-item-text\"><div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_column et_pb_column_3_4 et_pb_column_2 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_dark\">\n<div class=\"et_pb_text_inner\">\u00c9liminer l'attitude du \u00ab&nbsp;ce n'est pas mon travail&nbsp;\u00bb.<\/div>\n<div class=\"et_pb_text_inner\">Winnie Chow, directrice des affaires juridiques<\/div>\n<div>\n<p>C'est un principe que j'ai appris et que j'ai pratiqu\u00e9 depuis mon enfance. Lorsque j'\u00e9tais une jeune enfant vivant \u00e0 Hong Kong, je me souviens tr\u00e8s bien que ma m\u00e8re me disait toujours que je devais non seulement faire ce qu'on me demandait, mais que je devais aussi faire plus que ce qu'on me demandait pour montrer que je comprends vraiment ce que je fais et pourquoi. Il est fort possible que ma m\u00e8re m'ait dit cela pendant que je faisais mes devoirs d'une mani\u00e8re moins qu'attentive&nbsp;!  <\/p>\n<p>Aujourd'hui, apr\u00e8s avoir travaill\u00e9 au service juridique d'OPEX pendant pr\u00e8s de 20&nbsp;ans, je peux vous dire que ce principe fait partie int\u00e9grante de ma vie professionnelle quotidienne. Bien que ma responsabilit\u00e9 principale soit de travailler sur divers types de transactions juridiques telles que les propositions de vente, les contrats d'achat ou les contrats de maintenance, je re\u00e7ois \u00e9galement des demandes non juridiques de nos clients au cours de mon travail avec eux.  <\/p>\n<p>Par exemple, j'ai r\u00e9cemment \u00e9t\u00e9 d\u00e9concert\u00e9e lorsqu'un client m'a demand\u00e9 comment nous emballions nos scanners, quels types de mat\u00e9riaux nous utilisions et si les mat\u00e9riaux \u00e9taient recyclables. Je n'en avais aucune id\u00e9e, mais je savais qui connaissait la r\u00e9ponse. J'ai appel\u00e9 l'un de mes coll\u00e8gues du service d'exp\u00e9dition et il m'a expliqu\u00e9 le processus et m'a fourni les informations sur l'emballage, que j'ai ensuite transmises \u00e0 notre client.  <\/p>\n<p>Au lieu de simplement renvoyer ces choses \u00e0 quelqu'un d'autre, je sais que je suis mieux en mesure de mener \u00e0 bien une transaction avec un client parce que nous nous entraidons. Cela contribue \u00e0 son tour au succ\u00e8s d'OPEX et m'aide (ainsi qu'\u00e0 d'autres) \u00e0 grandir et \u00e0 apprendre dans le processus. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      \n          \n    \t  \n              <a href=\"#\" class=\"uc_btn uc_more_btn\" >En savoir plus<\/a>\n                        \n      <\/div> \n<\/div>\n\n  <\/div>\n<\/div>\n\n\n<!-- end Content Accordion -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dda4421 elementor-widget elementor-widget-spacer\" data-id=\"7dda4421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-413ed39e e-flex e-con-boxed e-con e-parent\" data-id=\"413ed39e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3b20279e e-con-full e-flex e-con e-child\" data-id=\"3b20279e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-622f8be4 elementor-widget elementor-widget-text-editor\" data-id=\"622f8be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"opex-label-strong opex-spacer-mbe-1 opex-spacer-ls-1\">OFFRES D&rsquo;EMPLOI<\/p>\n\n<h2 class=\"opex-spacer-mbs-0\">B\u00e2tir une carri\u00e8re chez OPEX<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2cc87986 e-con-full e-flex e-con e-child\" data-id=\"2cc87986\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7d1a49 elementor-widget elementor-widget-text-editor\" data-id=\"5d7d1a49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Souhaitez-vous faire partie de la prochaine vague de technologie et travailler pour une entreprise qui valorise ses employ\u00e9s ? Nous pensons qu&rsquo;en investissant dans notre \u00e9quipe, nous pouvons r\u00e9aliser de grandes choses ensemble. Si vous souhaitez faire partie d&rsquo;une \u00e9quipe dynamique et avant-gardiste, jetez un coup d&rsquo;\u0153il \u00e0 nos opportunit\u00e9s actuelles !  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b278b8a opex-button-dark elementor-widget elementor-widget-button\" data-id=\"6b278b8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/devopexcom.wpengine.com\/careers\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Explorer les opportunit\u00e9s de carri\u00e8re<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-573e231 e-flex e-con-boxed e-con e-parent\" data-id=\"573e231\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 propos d&rsquo;OPEX Valeurs et principes Valeurs Int\u00e9grit\u00e9 Int\u00e9grit\u00e9 Par : Dave Stevens, Pr\u00e9sident-directeur g\u00e9n\u00e9ral \u00ab Je recherche trois qualit\u00e9s lors du recrutement. La premi\u00e8re est l&rsquo;int\u00e9grit\u00e9 personnelle, la deuxi\u00e8me est l&rsquo;intelligence, et la troisi\u00e8me est un niveau d&rsquo;\u00e9nergie \u00e9lev\u00e9. Mais sans la premi\u00e8re, les deux autres vous d\u00e9truiront. \u00bb \u2013Warren Buffett Au c\u0153ur de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-9004111222937059","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Valeurs et principes de r\u00e9ussite d&#039;OPEX - OPEX<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les valeurs fondamentales d&#039;OPEX : int\u00e9grit\u00e9, v\u00e9rit\u00e9 et \u00e9quit\u00e9 qui animent notre culture d&#039;entreprise. D\u00e9couvrez comment nous privil\u00e9gions l&#039;humain avant la position dans chaque d\u00e9cision.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valeurs et principes\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les valeurs fondamentales d&#039;OPEX : int\u00e9grit\u00e9, v\u00e9rit\u00e9 et \u00e9quit\u00e9 qui animent notre culture d&#039;entreprise. D\u00e9couvrez comment nous privil\u00e9gions l&#039;humain avant la position dans chaque d\u00e9cision.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/\" \/>\n<meta property=\"og:site_name\" content=\"OPEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OPEXCorp\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T00:38:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OPEXcorporation\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/valeurs-et-principes\\\/\",\"url\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/valeurs-et-principes\\\/\",\"name\":\"Valeurs et principes de r\u00e9ussite d'OPEX - OPEX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-03-04T19:05:48+00:00\",\"dateModified\":\"2026-04-22T00:38:57+00:00\",\"description\":\"D\u00e9couvrez les valeurs fondamentales d'OPEX : int\u00e9grit\u00e9, v\u00e9rit\u00e9 et \u00e9quit\u00e9 qui animent notre culture d'entreprise. D\u00e9couvrez comment nous privil\u00e9gions l'humain avant la position dans chaque d\u00e9cision.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/valeurs-et-principes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.opex.com\\\/fr\\\/valeurs-et-principes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/valeurs-et-principes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valeurs et principes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/\",\"name\":\"OPEX\",\"description\":\"Next Generation Automation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/#organization\",\"name\":\"OPEX Corporation\",\"alternateName\":\"OPEX Corporation\",\"url\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-opex-blue.svg\",\"contentUrl\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-opex-blue.svg\",\"caption\":\"OPEX Corporation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OPEXCorp\\\/\",\"https:\\\/\\\/x.com\\\/OPEXcorporation\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/opex-corporation\\\/\",\"https:\\\/\\\/www.instagram.com\\\/opexcorporation\\\/\"],\"email\":\"info@opex.com\",\"telephone\":\"+1-856-727-1100\",\"legalName\":\"OPEX Corporation\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1001\",\"maxValue\":\"5000\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Valeurs et principes de r\u00e9ussite d'OPEX - OPEX","description":"D\u00e9couvrez les valeurs fondamentales d'OPEX : int\u00e9grit\u00e9, v\u00e9rit\u00e9 et \u00e9quit\u00e9 qui animent notre culture d'entreprise. D\u00e9couvrez comment nous privil\u00e9gions l'humain avant la position dans chaque d\u00e9cision.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/","og_locale":"fr_FR","og_type":"article","og_title":"Valeurs et principes","og_description":"D\u00e9couvrez les valeurs fondamentales d'OPEX : int\u00e9grit\u00e9, v\u00e9rit\u00e9 et \u00e9quit\u00e9 qui animent notre culture d'entreprise. D\u00e9couvrez comment nous privil\u00e9gions l'humain avant la position dans chaque d\u00e9cision.","og_url":"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/","og_site_name":"OPEX","article_publisher":"https:\/\/www.facebook.com\/OPEXCorp\/","article_modified_time":"2026-04-22T00:38:57+00:00","twitter_card":"summary_large_image","twitter_site":"@OPEXcorporation","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/","url":"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/","name":"Valeurs et principes de r\u00e9ussite d'OPEX - OPEX","isPartOf":{"@id":"https:\/\/www.opex.com\/fr\/#website"},"datePublished":"2024-03-04T19:05:48+00:00","dateModified":"2026-04-22T00:38:57+00:00","description":"D\u00e9couvrez les valeurs fondamentales d'OPEX : int\u00e9grit\u00e9, v\u00e9rit\u00e9 et \u00e9quit\u00e9 qui animent notre culture d'entreprise. D\u00e9couvrez comment nous privil\u00e9gions l'humain avant la position dans chaque d\u00e9cision.","breadcrumb":{"@id":"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.opex.com\/fr\/valeurs-et-principes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.opex.com\/fr\/valeurs-et-principes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.opex.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Valeurs et principes"}]},{"@type":"WebSite","@id":"https:\/\/www.opex.com\/fr\/#website","url":"https:\/\/www.opex.com\/fr\/","name":"OPEX","description":"Next Generation Automation","publisher":{"@id":"https:\/\/www.opex.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.opex.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.opex.com\/fr\/#organization","name":"OPEX Corporation","alternateName":"OPEX Corporation","url":"https:\/\/www.opex.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.opex.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.opex.com\/wp-content\/uploads\/2024\/01\/logo-opex-blue.svg","contentUrl":"https:\/\/www.opex.com\/wp-content\/uploads\/2024\/01\/logo-opex-blue.svg","caption":"OPEX Corporation"},"image":{"@id":"https:\/\/www.opex.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OPEXCorp\/","https:\/\/x.com\/OPEXcorporation","https:\/\/www.linkedin.com\/company\/opex-corporation\/","https:\/\/www.instagram.com\/opexcorporation\/"],"email":"info@opex.com","telephone":"+1-856-727-1100","legalName":"OPEX Corporation","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1001","maxValue":"5000"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/pages\/9004111222937059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/comments?post=9004111222937059"}],"version-history":[{"count":4,"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/pages\/9004111222937059\/revisions"}],"predecessor-version":[{"id":9004111222947052,"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/pages\/9004111222937059\/revisions\/9004111222947052"}],"wp:attachment":[{"href":"https:\/\/www.opex.com\/fr\/wp-json\/wp\/v2\/media?parent=9004111222937059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}