{"id":9004111222946198,"date":"2025-02-04T10:07:40","date_gmt":"2025-02-04T15:07:40","guid":{"rendered":"https:\/\/www.opex.com\/unkategorisiert\/weltklasse-technologie-lokale-expertise\/"},"modified":"2026-04-01T16:16:04","modified_gmt":"2026-04-01T20:16:04","slug":"weltklasse-technologie-lokale-expertise","status":"publish","type":"post","link":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/","title":{"rendered":"Weltklasse-Technologie. Lokale Expertise."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9004111222946198\" class=\"elementor elementor-9004111222946198 elementor-9004111222911816\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e029fb3 opex-hero e-flex e-con-boxed e-con e-child\" data-id=\"1e029fb3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4fb40c90 e-con-full e-flex e-con e-child\" data-id=\"4fb40c90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2de1327e elementor-widget elementor-widget-button\" data-id=\"2de1327e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/ressourcen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-chevron-left\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur\u00fcck zu den Ressourcen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aa76b95 elementor-widget elementor-widget-heading\" data-id=\"4aa76b95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Weltklasse-Technologie, lokale Expertise<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-401f228b elementor-widget elementor-widget-text-editor\" data-id=\"401f228b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4,5-Min.-Video<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62904d89 e-con-full opex-post-summary e-flex e-con e-child\" data-id=\"62904d89\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2397e135 elementor-widget elementor-widget-heading\" data-id=\"2397e135\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entdecken Sie unsere EMEA-Zentrale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a0973a6 e-flex e-con-boxed e-con e-parent\" data-id=\"1a0973a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56403a03 e-flex e-con-boxed e-con e-child\" data-id=\"56403a03\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5d876960 opex-post-detail-content e-flex e-con-boxed e-con e-child\" data-id=\"5d876960\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4561d93c elementor-widget elementor-widget-video\" data-id=\"4561d93c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/1042930322?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d719f2e e-flex e-con-boxed e-con e-parent\" data-id=\"d719f2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61ba47ae elementor-widget__width-initial elementor-fixed opex-back-to-top elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"61ba47ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_opacity_effect&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;viewport&quot;,&quot;motion_fx_opacity_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_opacity_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_opacity_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#content\" aria-label=\"Back To Top\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-arrow-up-long\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c6d6f45 opex-carousel-with-vertical-cards opex-breakout-right opex-excluded e-flex e-con-boxed e-con e-parent\" data-id=\"4c6d6f45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7a2df7e3 e-con-full e-flex e-con e-child\" data-id=\"7a2df7e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c8fc1a2 elementor-widget elementor-widget-heading\" data-id=\"1c8fc1a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weitere Ressourcen, die Sie hilfreich finden k\u00f6nnten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39804738 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"39804738\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27cb7ae1 elementor-widget elementor-widget-ucaddon_arrow_navigation\" data-id=\"27cb7ae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_arrow_navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Remote Arrows -->\n\t\t<link id='font-awesome-css' href='https:\/\/www.opex.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/www.opex.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Remote Arrows *\/\n\n.ue-remote-carousel-navigation-wrapper\n{\n  display:flex;\n}\n\n.ue-remote-carousel-navigation-wrapper .ue-remote-arrow\n{\n  border:none;\n  border-color:transparent;\n}\n\n.ue-remote-carousel-navigation-wrapper .ue-remote-arrow:hover\n{\n  background-color:transparent;\n \n}\n\n\n#uc_arrow_navigation_elementor_27cb7ae1\n{\n  display:inline-flex;\n}\n\n#uc_arrow_navigation_elementor_27cb7ae1 .ue-remote-arrow\n{\n  flex-grow:0;\n  flex-shrink:0;\n  transition:0.3s;\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  cursor:pointer;\n}\n\n\n#uc_arrow_navigation_elementor_27cb7ae1 .ue-remote-arrow .ue-carousel-nav-icon\n{\n  transition:0.3s;\n  line-height:1em;\n}\n\n#uc_arrow_navigation_elementor_27cb7ae1 .ue-remote-arrow .ue-carousel-nav-icon svg\n{\n  transition:0.3s;\n  height:1em;\n  width:1em;\n}\n\n\n#uc_arrow_navigation_elementor_27cb7ae1 .ue-carousel-nav-label\n{\n  transition:0.3s;\n}\n\n#uc_arrow_navigation_elementor_27cb7ae1 .uc-disabled{\n\topacity: 0.3;\n}\n\n<\/style>\n\n<div class=\"ue-remote-carousel-navigation-wrapper\">\n<div id=\"uc_arrow_navigation_elementor_27cb7ae1\" class=\"ue-remote-carousel-navigation\"  data-parentid='auto'>\n  \n  \n  \n\t<div class=\"ue-remote-arrow ue-carousel-prev \">\n    <div class=\"ue-carousel-nav-icon\"><i class='icon icon-arrow-left-long'><\/i><\/div>\n    \t\n  <\/div>   \n\t\n\n  \n \n\n  <div class=\"ue-remote-arrow ue-carousel-next \">\n        <div class=\"ue-carousel-nav-icon\"><i class='icon icon-arrow-right-long'><\/i><\/div>\n  <\/div>\n  \n  \n<\/div>\n<\/div>\n<!-- end Remote Arrows -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43490bda elementor-widget elementor-widget-ucaddon_remote_counter_display\" data-id=\"43490bda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_remote_counter_display.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Remote Counter -->\n<style>\/* widget: Remote Counter *\/\n\n#uc_remote_counter_display_elementor_43490bda\n{\n  display:flex;\n}\n\n<\/style>\n\n<div id=\"uc_remote_counter_display_elementor_43490bda\" class=\"remote_counter_display\"  data-parentid='auto'>\n  <div class=\"ue-counter-current\"><\/div> \n    <div class=\"ue-counter-separator\">\/<\/div>\n      <div class=\"ue-counter-total\"><\/div>\n  \t\n<\/div>\n<!-- end Remote Counter -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-335bcb1b e-con-full e-flex e-con e-child\" data-id=\"335bcb1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c0661c1 elementor-widget elementor-widget-ucaddon_content_carousel_new_vertical_cards\" data-id=\"7c0661c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_content_carousel_new_vertical_cards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Carousel (Vertical Cards) -->\n\t\t<link id='owl-carousel-css' href='https:\/\/www.opex.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='fancybox-css' href='https:\/\/www.opex.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/fancybox3\/jquery.fancybox.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Content Carousel (Vertical Cards) *\/\n\n.ue-content-carousel\n{\n  min-height:1px;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .ue-item\n{\n  transition:0.3s;\n  position:relative;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .carousel-image\n{\n  transition:0.3s;\n}\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1{\n  position:relative;\n  min-height:1px;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .ue-content-holder\n{\n  display:flex;\n  flex-direction:column;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .ue-btn-holder\n{\n  margin-top:auto;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .owl-nav .owl-prev{\n    position:absolute;\n    display:inline-block;\n    text-align:center;\n}\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .owl-nav .owl-next{\n  position:absolute;\n  display:inline-block;\n  text-align:center;\n}\n\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .owl-dots {\noverflow:hidden;\ntext-align:center;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .owl-dot {\nborder-radius:50%;\ndisplay:inline-block;\n}\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .uc_image_carousel_container_holder{\n  overflow:hidden;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .uc_more_btn{\n  \n    display:inline-block;\n  text-decoration:none;\n  text-align:center;\n  transition:0.3s;\n}\n\n\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .uc_date{\n  color:gray;\n  padding-top:10px;\n  text-style:italic;\n}\n\n\n\n\n\n\n\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .ue-btn-inner-wrapper\n{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .ue-btn-inner-wrapper svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .uc_image_carousel_placeholder\n{\n  position:relative;\n}\n\n#uc_content_carousel_new_vertical_cards_elementor_7c0661c1 .ue_img_link\n{\n  display:block;\n  position:absolute;\n  top:0px;\n  right:0px;\n  left:0px;\n  bottom:0px;\n}\n\n<\/style>\n\n<div class=\"ue-content-carousel\" >\n   <div class=\"uc_carousel owl-carousel owl-theme uc-items-wrapper  uc-remote-parent  \" id=\"uc_content_carousel_new_vertical_cards_elementor_7c0661c1\" data-lightbox=\"false\" data-equal-height=\"true\"  data-remoteid='auto' data-widgetname='Content Carousel (Vertical Cards)' >\n   \t\t<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2026\/02\/The-Role-of-Sustainability-in-Logistics-1-1-768x512.jpeg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Aufbau einer umweltfreundlicheren Lieferkette Die Rolle der Nachhaltigkeit in der Logistik<\/h3>\n                            <div class=\"ue-text\" >E-Book<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/%e3%83%9b%e3%83%af%e3%82%a4%e3%83%88%e3%83%9a%e3%83%bc%e3%83%91%e3%83%bc\/nachhaltige-supply-chain-logistik\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2026\/02\/Optimising-Operations-Strategies-for-Efficiency-and-Cost-Control-in-UK-Logistics-768x513.jpeg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Optimierung der Betriebsabl\u00e4ufe: Strategien f\u00fcr Effizienz und Kostenkontrolle in der britischen Logistikbranche<\/h3>\n                            <div class=\"ue-text\" >E-Book<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/%e3%83%9b%e3%83%af%e3%82%a4%e3%83%88%e3%83%9a%e3%83%bc%e3%83%91%e3%83%bc\/strategien-fur-effizienz-und-kostenkontrolle-in-der-logistik\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/08\/Cooksongold-Featured-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Cooksongold optimiert den Fulfillment-Prozess f\u00fcr seine Mitarbeitenden und setzt dabei auf den Goldstandard der Automatisierung<\/h3>\n                            <div class=\"ue-text\" >Warehouse Automation<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/unkategorisiert\/verbesserung-der-auftragsabwicklung-bei-cooksongold\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/07\/record-partners-featured-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Record Partners bietet hochvolumige Digitalisierung kritischer Akten mit neuer Technologie<\/h3>\n                            <div class=\"ue-text\" >Fallstudie<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/fallstudie\/record-partners-bietet-digitalisierung\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/07\/OPX_235_PostDetail_HeroTemplate_LargeScreen_2x-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Deutsche Logistik-Arbeitskr\u00e4ftestrategien: Resilienz durch intelligente Automatisierung<\/h3>\n                            <div class=\"ue-text\" >E-Book<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/e-book\/logistikbelegschaft-deutschland\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/07\/Investing-in-Sustainability-Addressing-the-Cost-Barrier-and-Seeking-Government-Support-feature-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">In die Nachhaltigkeit investieren: \u00dcberwindung der Kostenbarriere und Suche nach staatlicher Unterst\u00fctzung<\/h3>\n                            <div class=\"ue-text\" >Einblicke<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/einblicke\/in-die-nachhaltigkeit-investieren-uberwindung-der-kostenbarriere-und-suche-nach-staatlicher-unterstutzung\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/07\/Integrating-ESG-Environmental-social-and-governance-into-Business-Strategy-Building-a-Sustainable-Future-feature-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">ESG in die Unternehmensstrategie integrieren<\/h3>\n                            <div class=\"ue-text\" >Einblicke<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/einblicke\/esg-unternehmensstrategie-logistik\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/07\/Building-a-Future-Ready-Workforce-The-Importance-of-Training-Apprenticeships-and-Career-Development-in-UK-Warehouses-Featured-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Aufbau einer zukunftssicheren Lagerbelegschaft in Deutschland | Strategien zur Personalentwicklung<\/h3>\n                            <div class=\"ue-text\" >Einblicke<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/einblicke\/aufbau-einer-zukunftssicheren-lagerbelegschaft\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/07\/Creating-A-Greener-Warehouse-Energy-Efficiency-Recycling-and-Environmental-Initiatives-Feature-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Ein gr\u00fcneres Lagerhaus schaffen: Energieeffizienz, Recycling und Umweltinitiativen<\/h3>\n                            <div class=\"ue-text\" >Einblicke<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/einblicke\/ein-grueneres-lagerhaus-schaffen-energieeffizienz-recycling-und-umweltinitiativen\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder ue-item\">\n    <div class=\"uc_image_carousel_placeholder\">\n    \n    <div style=\"background-image:url(https:\/\/www.opex.com\/wp-content\/uploads\/2025\/07\/Why-ESG-Matters-Meeting-Customer-Expectations-and-Enhancing-Corporate-Reputation-Feature-768x428.jpg);background-position:center; background-repeat:no-repeat;\" class=\"carousel-image\"><\/div>\n    \n        \n        \n  <\/div>\n  \n    <div class=\"uc_image_carousel_content content-padding ue-content-holder\">\n    \n            <div style=\"width:100%;\">\n                                <h3 class=\"ue-title\">Warum ESG wichtig ist: Kundenerwartungen erf\u00fcllen und den Ruf des Unternehmens verbessern<\/h3>\n                            <div class=\"ue-text\" >Einblicke<\/div>        <\/div>\n       \n    \n    \n    \n    <!-- put your not empty html here -->\n\n    \n    \n                  <div class=\"opex-item-bottom-wrapper\">\n    \t\t<div class=\"ue-btn-holder\" style=\"width:100%;\">\n                              <a class=\"ue-btn uc_more_btn ue-dynamic-popup-single \" href='https:\/\/www.opex.com\/de\/einblicke\/warum-esg-wichtig-ist-kundenerwartungen-erfuellen-und-den-ruf-des-unternehmens-verbessern\/'>\n                  \n                 <div class=\"ue-btn-inner-wrapper\">\n                                 \t\t<div class=\"ue-btn-inner-txt\">Erfahren Sie mehr<\/div>\n                                      \n                   <div class=\"ue-btn-inner-icon\"><i class='icon icon-arrow-right'><\/i><\/div>                   \n                 <\/div>\n               <\/a>\n            <\/div>\n            <div class=\"opex-read-time\">\n              <p><\/p>\n            <\/div>\n          <\/div>\n            \n  \n    \n    \n          \n        \n      <\/div>\n  <\/div>\n\n   <\/div>\t\n<\/div>\n<!-- end Content Carousel (Vertical Cards) -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcb4865 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-child\" data-id=\"dcb4865\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66bb15d3 elementor-widget elementor-widget-ucaddon_arrow_navigation\" data-id=\"66bb15d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_arrow_navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Remote Arrows -->\n\n<style>\/* widget: Remote Arrows *\/\n\n.ue-remote-carousel-navigation-wrapper\n{\n  display:flex;\n}\n\n.ue-remote-carousel-navigation-wrapper .ue-remote-arrow\n{\n  border:none;\n  border-color:transparent;\n}\n\n.ue-remote-carousel-navigation-wrapper .ue-remote-arrow:hover\n{\n  background-color:transparent;\n \n}\n\n\n#uc_arrow_navigation_elementor_66bb15d3\n{\n  display:inline-flex;\n}\n\n#uc_arrow_navigation_elementor_66bb15d3 .ue-remote-arrow\n{\n  flex-grow:0;\n  flex-shrink:0;\n  transition:0.3s;\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  cursor:pointer;\n}\n\n\n#uc_arrow_navigation_elementor_66bb15d3 .ue-remote-arrow .ue-carousel-nav-icon\n{\n  transition:0.3s;\n  line-height:1em;\n}\n\n#uc_arrow_navigation_elementor_66bb15d3 .ue-remote-arrow .ue-carousel-nav-icon svg\n{\n  transition:0.3s;\n  height:1em;\n  width:1em;\n}\n\n\n#uc_arrow_navigation_elementor_66bb15d3 .ue-carousel-nav-label\n{\n  transition:0.3s;\n}\n\n#uc_arrow_navigation_elementor_66bb15d3 .uc-disabled{\n\topacity: 0.3;\n}\n\n<\/style>\n\n<div class=\"ue-remote-carousel-navigation-wrapper\">\n<div id=\"uc_arrow_navigation_elementor_66bb15d3\" class=\"ue-remote-carousel-navigation\"  data-parentid='auto'>\n  \n  \n  \n\t<div class=\"ue-remote-arrow ue-carousel-prev \">\n    <div class=\"ue-carousel-nav-icon\"><i class='icon icon-arrow-left-long'><\/i><\/div>\n    \t\n  <\/div>   \n\t\n\n  \n \n\n  <div class=\"ue-remote-arrow ue-carousel-next \">\n        <div class=\"ue-carousel-nav-icon\"><i class='icon icon-arrow-right-long'><\/i><\/div>\n  <\/div>\n  \n  \n<\/div>\n<\/div>\n<!-- end Remote Arrows -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66afa92 elementor-widget elementor-widget-ucaddon_remote_counter_display\" data-id=\"66afa92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_remote_counter_display.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Remote Counter -->\n<style>\/* widget: Remote Counter *\/\n\n#uc_remote_counter_display_elementor_66afa92\n{\n  display:flex;\n}\n\n<\/style>\n\n<div id=\"uc_remote_counter_display_elementor_66afa92\" class=\"remote_counter_display\"  data-parentid='auto'>\n  <div class=\"ue-counter-current\"><\/div> \n    <div class=\"ue-counter-separator\">\/<\/div>\n      <div class=\"ue-counter-total\"><\/div>\n  \t\n<\/div>\n<!-- end Remote Counter -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cb47c2f opex-excluded e-flex e-con-boxed e-con e-parent\" data-id=\"3cb47c2f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-22aff15c e-con-full e-flex e-con e-child\" data-id=\"22aff15c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40baa53c elementor-widget elementor-widget-text-editor\" data-id=\"40baa53c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"opex-label-strong opex-spacer-mbe-1\">AUTOMATION DER N\u00c4CHSTEN STUFE<\/p>\n\n<h2 class=\"opex-spacer-mbs-0\">Erschlie\u00dfen Sie betriebliche Effizienz mit OPEX<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-299d2497 e-con-full e-flex e-con e-child\" data-id=\"299d2497\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d780874 elementor-widget elementor-widget-text-editor\" data-id=\"5d780874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>OPEX treibt die Zukunft der Automation voran. Kontaktieren Sie uns, um mehr dar\u00fcber zu erfahren, wie unsere vertikal integrierten automatisierten L\u00f6sungen Ihrem Unternehmen zu neuen H\u00f6hen verhelfen k\u00f6nnen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d1fa687 opex-button-dark elementor-widget elementor-widget-button\" data-id=\"1d1fa687\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LASSEN SIE UNS ZUSAMMENARBEITEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Zur\u00fcck zu den Ressourcen Weltklasse-Technologie, lokale Expertise 4,5-Min.-Video Entdecken Sie unsere EMEA-Zentrale Weitere Ressourcen, die Sie hilfreich finden k\u00f6nnten \/* widget: Remote Arrows *\/ .ue-remote-carousel-navigation-wrapper { display:flex; } .ue-remote-carousel-navigation-wrapper .ue-remote-arrow { border:none; border-color:transparent; } .ue-remote-carousel-navigation-wrapper .ue-remote-arrow:hover { background-color:transparent; } #uc_arrow_navigation_elementor_27cb7ae111 { display:inline-flex; } #uc_arrow_navigation_elementor_27cb7ae111 .ue-remote-arrow { flex-grow:0; flex-shrink:0; transition:0.3s; display:inline-flex; align-items:center; justify-content:center; line-height:1em; cursor:pointer; } [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9004111222911830,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[9004111222905854],"tags":[],"class_list":["post-9004111222946198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video","solution-warehouse-automation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Weltklasse-Technologie. Lokale Expertise. - OPEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weltklasse-Technologie. Lokale Expertise.\" \/>\n<meta property=\"og:description\" content=\"Zur\u00fcck zu den Ressourcen Weltklasse-Technologie, lokale Expertise 4,5-Min.-Video Entdecken Sie unsere EMEA-Zentrale Weitere Ressourcen, die Sie hilfreich finden k\u00f6nnten \/* widget: Remote Arrows *\/ .ue-remote-carousel-navigation-wrapper { display:flex; } .ue-remote-carousel-navigation-wrapper .ue-remote-arrow { border:none; border-color:transparent; } .ue-remote-carousel-navigation-wrapper .ue-remote-arrow:hover { background-color:transparent; } #uc_arrow_navigation_elementor_27cb7ae111 { display:inline-flex; } #uc_arrow_navigation_elementor_27cb7ae111 .ue-remote-arrow { flex-grow:0; flex-shrink:0; transition:0.3s; display:inline-flex; align-items:center; justify-content:center; line-height:1em; cursor:pointer; } [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/\" \/>\n<meta property=\"og:site_name\" content=\"OPEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OPEXCorp\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-04T15:07:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T20:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.opex.com\/wp-content\/uploads\/2025\/02\/EMEA-Video-Featured-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matt Dowis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OPEXcorporation\" \/>\n<meta name=\"twitter:site\" content=\"@OPEXcorporation\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matt Dowis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/\"},\"author\":{\"name\":\"Matt Dowis\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#\\\/schema\\\/person\\\/7164aed324521bfa77bee9b87ec71c8e\"},\"headline\":\"Weltklasse-Technologie. Lokale Expertise.\",\"datePublished\":\"2025-02-04T15:07:40+00:00\",\"dateModified\":\"2026-04-01T20:16:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/\"},\"wordCount\":656,\"publisher\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/EMEA-Video-Featured-scaled.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/\",\"url\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/\",\"name\":\"Weltklasse-Technologie. Lokale Expertise. - OPEX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/EMEA-Video-Featured-scaled.jpg\",\"datePublished\":\"2025-02-04T15:07:40+00:00\",\"dateModified\":\"2026-04-01T20:16:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/EMEA-Video-Featured-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/EMEA-Video-Featured-scaled.jpg\",\"width\":2560,\"height\":1428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/video\\\/weltklasse-technologie-lokale-expertise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.opex.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weltklasse-Technologie. Lokale Expertise.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.opex.com\\\/de\\\/\",\"name\":\"OPEX\",\"description\":\"Next Generation Automation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.opex.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#organization\",\"name\":\"OPEX Corporation\",\"alternateName\":\"OPEX Corporation\",\"url\":\"https:\\\/\\\/www.opex.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-opex-blue.svg\",\"contentUrl\":\"https:\\\/\\\/www.opex.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-opex-blue.svg\",\"caption\":\"OPEX Corporation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OPEXCorp\\\/\",\"https:\\\/\\\/x.com\\\/OPEXcorporation\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/opex-corporation\\\/\",\"https:\\\/\\\/www.instagram.com\\\/opexcorporation\\\/\"],\"email\":\"info@opex.com\",\"telephone\":\"+1-856-727-1100\",\"legalName\":\"OPEX Corporation\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1001\",\"maxValue\":\"5000\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.opex.com\\\/de\\\/#\\\/schema\\\/person\\\/7164aed324521bfa77bee9b87ec71c8e\",\"name\":\"Matt Dowis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7de5fd4fc31f172a9732567de3b805013af9a4827d8f111c8701477348506e3f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7de5fd4fc31f172a9732567de3b805013af9a4827d8f111c8701477348506e3f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7de5fd4fc31f172a9732567de3b805013af9a4827d8f111c8701477348506e3f?s=96&d=mm&r=g\",\"caption\":\"Matt Dowis\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Weltklasse-Technologie. Lokale Expertise. - OPEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/","og_locale":"de_DE","og_type":"article","og_title":"Weltklasse-Technologie. Lokale Expertise.","og_description":"Zur\u00fcck zu den Ressourcen Weltklasse-Technologie, lokale Expertise 4,5-Min.-Video Entdecken Sie unsere EMEA-Zentrale Weitere Ressourcen, die Sie hilfreich finden k\u00f6nnten \/* widget: Remote Arrows *\/ .ue-remote-carousel-navigation-wrapper { display:flex; } .ue-remote-carousel-navigation-wrapper .ue-remote-arrow { border:none; border-color:transparent; } .ue-remote-carousel-navigation-wrapper .ue-remote-arrow:hover { background-color:transparent; } #uc_arrow_navigation_elementor_27cb7ae111 { display:inline-flex; } #uc_arrow_navigation_elementor_27cb7ae111 .ue-remote-arrow { flex-grow:0; flex-shrink:0; transition:0.3s; display:inline-flex; align-items:center; justify-content:center; line-height:1em; cursor:pointer; } [&hellip;]","og_url":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/","og_site_name":"OPEX","article_publisher":"https:\/\/www.facebook.com\/OPEXCorp\/","article_published_time":"2025-02-04T15:07:40+00:00","article_modified_time":"2026-04-01T20:16:04+00:00","og_image":[{"width":2560,"height":1428,"url":"https:\/\/www.opex.com\/wp-content\/uploads\/2025\/02\/EMEA-Video-Featured-scaled.jpg","type":"image\/jpeg"}],"author":"Matt Dowis","twitter_card":"summary_large_image","twitter_creator":"@OPEXcorporation","twitter_site":"@OPEXcorporation","twitter_misc":{"Verfasst von":"Matt Dowis","Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/#article","isPartOf":{"@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/"},"author":{"name":"Matt Dowis","@id":"https:\/\/www.opex.com\/de\/#\/schema\/person\/7164aed324521bfa77bee9b87ec71c8e"},"headline":"Weltklasse-Technologie. Lokale Expertise.","datePublished":"2025-02-04T15:07:40+00:00","dateModified":"2026-04-01T20:16:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/"},"wordCount":656,"publisher":{"@id":"https:\/\/www.opex.com\/de\/#organization"},"image":{"@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opex.com\/wp-content\/uploads\/2025\/02\/EMEA-Video-Featured-scaled.jpg","articleSection":["Video"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/","url":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/","name":"Weltklasse-Technologie. Lokale Expertise. - OPEX","isPartOf":{"@id":"https:\/\/www.opex.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/#primaryimage"},"image":{"@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opex.com\/wp-content\/uploads\/2025\/02\/EMEA-Video-Featured-scaled.jpg","datePublished":"2025-02-04T15:07:40+00:00","dateModified":"2026-04-01T20:16:04+00:00","breadcrumb":{"@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/#primaryimage","url":"https:\/\/www.opex.com\/wp-content\/uploads\/2025\/02\/EMEA-Video-Featured-scaled.jpg","contentUrl":"https:\/\/www.opex.com\/wp-content\/uploads\/2025\/02\/EMEA-Video-Featured-scaled.jpg","width":2560,"height":1428},{"@type":"BreadcrumbList","@id":"https:\/\/www.opex.com\/de\/video\/weltklasse-technologie-lokale-expertise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.opex.com\/de\/"},{"@type":"ListItem","position":2,"name":"Weltklasse-Technologie. Lokale Expertise."}]},{"@type":"WebSite","@id":"https:\/\/www.opex.com\/de\/#website","url":"https:\/\/www.opex.com\/de\/","name":"OPEX","description":"Next Generation Automation","publisher":{"@id":"https:\/\/www.opex.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.opex.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.opex.com\/de\/#organization","name":"OPEX Corporation","alternateName":"OPEX Corporation","url":"https:\/\/www.opex.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.opex.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.opex.com\/wp-content\/uploads\/2024\/01\/logo-opex-blue.svg","contentUrl":"https:\/\/www.opex.com\/wp-content\/uploads\/2024\/01\/logo-opex-blue.svg","caption":"OPEX Corporation"},"image":{"@id":"https:\/\/www.opex.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OPEXCorp\/","https:\/\/x.com\/OPEXcorporation","https:\/\/www.linkedin.com\/company\/opex-corporation\/","https:\/\/www.instagram.com\/opexcorporation\/"],"email":"info@opex.com","telephone":"+1-856-727-1100","legalName":"OPEX Corporation","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1001","maxValue":"5000"}},{"@type":"Person","@id":"https:\/\/www.opex.com\/de\/#\/schema\/person\/7164aed324521bfa77bee9b87ec71c8e","name":"Matt Dowis","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/7de5fd4fc31f172a9732567de3b805013af9a4827d8f111c8701477348506e3f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7de5fd4fc31f172a9732567de3b805013af9a4827d8f111c8701477348506e3f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7de5fd4fc31f172a9732567de3b805013af9a4827d8f111c8701477348506e3f?s=96&d=mm&r=g","caption":"Matt Dowis"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/posts\/9004111222946198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/comments?post=9004111222946198"}],"version-history":[{"count":2,"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/posts\/9004111222946198\/revisions"}],"predecessor-version":[{"id":9004111222946200,"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/posts\/9004111222946198\/revisions\/9004111222946200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/media\/9004111222911830"}],"wp:attachment":[{"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/media?parent=9004111222946198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/categories?post=9004111222946198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opex.com\/de\/wp-json\/wp\/v2\/tags?post=9004111222946198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}